{"id":3873,"date":"2025-07-29T10:36:52","date_gmt":"2025-07-29T08:36:52","guid":{"rendered":"https:\/\/pcr-legal.pl\/%d0%ba%d0%b0%d1%80%d1%82%d0%b0-%d0%bf%d0%be%d0%b1%d1%8b%d1%82%d0%b0\/"},"modified":"2025-11-12T12:47:11","modified_gmt":"2025-11-12T11:47:11","slug":"%d0%ba%d0%b0%d1%80%d1%82%d0%b0-%d0%bf%d0%be%d0%b1%d1%8b%d1%82%d0%b0","status":"publish","type":"page","link":"https:\/\/old.pcr-legal.pl\/es\/%d0%ba%d0%b0%d1%80%d1%82%d0%b0-%d0%bf%d0%be%d0%b1%d1%8b%d1%82%d0%b0\/","title":{"rendered":"Permiso de residencia"},"content":{"rendered":"<style>.kadence-column3309_eec369-a3 > .kt-inside-inner-col,.kadence-column3309_eec369-a3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3309_eec369-a3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_eec369-a3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_eec369-a3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_eec369-a3 > .kt-inside-inner-col{background-color:#ffffff;background-image:url('https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2024\/01\/05.png');background-size:cover;background-position:48% 52%;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column3309_eec369-a3 > .kt-inside-inner-col:before{opacity:0.52;background-color:var(--global-palette4, #2D3748);}.kadence-column3309_eec369-a3{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_eec369-a3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_eec369-a3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_eec369-a3 kvs-sm-false kb-section-has-overlay\"><div class=\"kt-inside-inner-col\">\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center has-theme-palette-9-color has-text-color has-link-color wp-elements-1\" style=\"font-size:86px;text-transform:none\">Permiso de residencia<\/h1>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n<style>.kadence-column3309_e6a034-83 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-3xl, 6.5rem);}.kadence-column3309_e6a034-83 > .kt-inside-inner-col,.kadence-column3309_e6a034-83 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3309_e6a034-83 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_e6a034-83 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_e6a034-83 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_e6a034-83 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3309_e6a034-83{text-align:left;}.kadence-column3309_e6a034-83{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_e6a034-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_e6a034-83 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_e6a034-83\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img data-dominant-color=\"8d8067\" data-has-transparency=\"true\" style=\"--dominant-color: #8d8067;\" loading=\"lazy\" decoding=\"async\" width=\"767\" height=\"326\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" src=\"https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2025\/09\/5-1.avif\" alt=\"\" class=\"wp-image-3473 has-transparency\" srcset=\"https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2025\/09\/5-1.avif 767w, https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2025\/09\/5-1-300x128.avif 300w\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Permiso de residencia<\/strong> (tarjeta de residencia) es un documento que permite a los extranjeros residir legalmente en Polonia por un per\u00edodo determinado, incluso hasta tres a\u00f1os. Adem\u00e1s, permite viajar libremente dentro del espacio Schengen sin necesidad de obtener visados adicionales.<\/p>\n<\/div>\n<\/div>\n\n\n<style>.kadence-column3309_3e23a6-26 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:25px;padding-left:10px;}.kadence-column3309_3e23a6-26 > .kt-inside-inner-col,.kadence-column3309_3e23a6-26 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3309_3e23a6-26 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_3e23a6-26 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_3e23a6-26 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_3e23a6-26 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3309_3e23a6-26{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_3e23a6-26 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_3e23a6-26 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_3e23a6-26 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3309_3da50e-1c .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-3309_3da50e-1c .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:40px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3309_3da50e-1c\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3309_2db22f-5a, .wp-block-kadence-advancedheading.kt-adv-heading3309_2db22f-5a[data-kb-block=\"kb-adv-heading3309_2db22f-5a\"]{margin-top:-10px;margin-right:0px;margin-bottom:0px;margin-left:0px;text-align:center;line-height:1em;font-weight:500;font-style:normal;font-family:Inter;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3309_2db22f-5a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3309_2db22f-5a[data-kb-block=\"kb-adv-heading3309_2db22f-5a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3309_2db22f-5a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3309_2db22f-5a[data-kb-block=\"kb-adv-heading3309_2db22f-5a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3309_2db22f-5a, .wp-block-kadence-advancedheading.kt-adv-heading3309_2db22f-5a[data-kb-block=\"kb-adv-heading3309_2db22f-5a\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading3309_2db22f-5a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3309_2db22f-5a\">\u00bfQUI\u00c9N PUEDE SOLICITAR EL PERMISO DE RESIDENCIA?<\/h4>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Puede solicitar el <strong>permiso de residencia temporal<\/strong> cualquier persona que:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se encuentre legalmente en el territorio de Polonia el d\u00eda de la presentaci\u00f3n de la solicitud.\u00a0<\/li>\n\n\n\n<li>Desee establecerse en Polonia por m\u00e1s tiempo del que permite el visado o el r\u00e9gimen de exenci\u00f3n de visado.\u00a0<\/li>\n\n\n\n<li>Tenga un objetivo concreto de estancia.<\/li>\n<\/ul>\n\n\n<style>.kadence-column3309_adb50b-0f > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:25px;padding-left:10px;}.kadence-column3309_adb50b-0f > .kt-inside-inner-col,.kadence-column3309_adb50b-0f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3309_adb50b-0f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_adb50b-0f > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_adb50b-0f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_adb50b-0f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3309_adb50b-0f{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_adb50b-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_adb50b-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_adb50b-0f inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3309_24dcae-3b .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-3309_24dcae-3b .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:40px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3309_24dcae-3b\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3309_c8f55a-d1, .wp-block-kadence-advancedheading.kt-adv-heading3309_c8f55a-d1[data-kb-block=\"kb-adv-heading3309_c8f55a-d1\"]{margin-top:-10px;margin-right:0px;margin-bottom:0px;margin-left:0px;text-align:center;line-height:1em;font-weight:500;font-style:normal;font-family:Inter;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3309_c8f55a-d1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3309_c8f55a-d1[data-kb-block=\"kb-adv-heading3309_c8f55a-d1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3309_c8f55a-d1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3309_c8f55a-d1[data-kb-block=\"kb-adv-heading3309_c8f55a-d1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3309_c8f55a-d1, .wp-block-kadence-advancedheading.kt-adv-heading3309_c8f55a-d1[data-kb-block=\"kb-adv-heading3309_c8f55a-d1\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading3309_c8f55a-d1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3309_c8f55a-d1\">BASES PARA SOLICITAR EL PERMISO DE RESIDENCIA<\/h4>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El permiso de residencia temporal puede concederse por distintos motivos, seg\u00fan el prop\u00f3sito de la estancia del extranjero. Estos son los motivos m\u00e1s frecuentes para solicitar el permiso de residencia temporal:\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Trabajo:<\/strong> Los extranjeros que han recibido una oferta de trabajo en Polonia pueden solicitar un permiso de residencia temporal en relaci\u00f3n con el empleo. Esto puede abarcar tanto a trabajadores asalariados como a personas que ejercen una actividad empresarial.<\/li>\n\n\n\n<li><strong>Estudios:<\/strong> Las personas que han iniciado estudios superiores en Polonia pueden solicitar el permiso de residencia temporal sobre la base de su condici\u00f3n de estudiantes.<\/li>\n\n\n\n<li><strong>Reagrupaci\u00f3n familiar:<\/strong><em>(y aqu\u00ed enlace a esa reagrupaci\u00f3n)\u00a0<\/em>: Los c\u00f3nyuges, hijos, padres u otros miembros de la familia de ciudadanos polacos o de extranjeros que posean un permiso de residencia pueden solicitar una tarjeta de residencia temporal con el fin de la reagrupaci\u00f3n familiar.<\/li>\n\n\n\n<li><strong>Actividad empresarial:<\/strong> Las personas que planean iniciar una actividad empresarial en Polonia o ya la tienen pueden solicitar el permiso de residencia temporal sobre esta base.<\/li>\n\n\n\n<li><strong>Protecci\u00f3n internacional:<\/strong> Los extranjeros que solicitan el estatuto de refugiado pueden recibir un permiso de residencia temporal mientras esperan la decisi\u00f3n sobre su solicitud.<\/li>\n\n\n\n<li><strong>Estancia sobre la base de un contrato de trabajo o de estudios:<\/strong> Los extranjeros que ya tienen un contrato de trabajo pueden solicitar el permiso de residencia temporal si cumplen determinadas condiciones relacionadas con el empleo.<\/li>\n<\/ul>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3309_e48713-c8{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id3309_e48713-c8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3309_e48713-c8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3309_e48713-c8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:1300px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3309_e48713-c8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3309_e48713-c8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3309_e48713-c8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3309_e48713-c8 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3309_72228c-33 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:25px;padding-left:10px;}.kadence-column3309_72228c-33 > .kt-inside-inner-col,.kadence-column3309_72228c-33 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3309_72228c-33 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_72228c-33 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_72228c-33 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_72228c-33 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3309_72228c-33{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_72228c-33 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_72228c-33 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_72228c-33 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3309_c889e5-dc .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-3309_c889e5-dc .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:40px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3309_c889e5-dc\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3309_9d4ec7-2a, .wp-block-kadence-advancedheading.kt-adv-heading3309_9d4ec7-2a[data-kb-block=\"kb-adv-heading3309_9d4ec7-2a\"]{margin-top:-10px;margin-right:0px;margin-bottom:0px;margin-left:0px;text-align:center;line-height:1em;font-weight:500;font-style:normal;font-family:Inter;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3309_9d4ec7-2a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3309_9d4ec7-2a[data-kb-block=\"kb-adv-heading3309_9d4ec7-2a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3309_9d4ec7-2a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3309_9d4ec7-2a[data-kb-block=\"kb-adv-heading3309_9d4ec7-2a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3309_9d4ec7-2a, .wp-block-kadence-advancedheading.kt-adv-heading3309_9d4ec7-2a[data-kb-block=\"kb-adv-heading3309_9d4ec7-2a\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading3309_9d4ec7-2a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3309_9d4ec7-2a\">\u00bfQU\u00c9 DOCUMENTOS SON NECESARIOS PARA LA SOLICITUD DEL PERMISO DE RESIDENCIA?<\/h4>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\">El proceso de presentar la <strong>solicitud de permiso de residencia temporal<\/strong> requiere normalmente preparar los siguientes documentos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>4 fotograf\u00edas de 35 mm x 45 mm.\u00a0<\/li>\n\n\n\n<li>Fotocopia de todo el pasaporte.\u00a0<\/li>\n\n\n\n<li>Solicitud de residencia temporal cumplimentada en polaco.\u00a0<\/li>\n\n\n\n<li>Seguro m\u00e9dico.\u00a0<\/li>\n\n\n\n<li>Documentos que acrediten la disponibilidad de medios econ\u00f3micos.\u00a0<\/li>\n\n\n\n<li>Justificante de la tasa administrativa por la presentaci\u00f3n de la solicitud (440 PLN o 340 PLN, seg\u00fan el prop\u00f3sito de la estancia).\u00a0<\/li>\n\n\n\n<li>Otros documentos seg\u00fan el prop\u00f3sito de la estancia.\u00a0<\/li>\n<\/ul>\n\n\n<style>.kadence-column3309_bd3a3c-16 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:25px;padding-left:10px;}.kadence-column3309_bd3a3c-16 > .kt-inside-inner-col,.kadence-column3309_bd3a3c-16 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3309_bd3a3c-16 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_bd3a3c-16 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_bd3a3c-16 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_bd3a3c-16 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3309_bd3a3c-16{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_bd3a3c-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_bd3a3c-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_bd3a3c-16 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3309_5a57a1-fb{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id3309_5a57a1-fb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3309_5a57a1-fb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3309_5a57a1-fb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:1300px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3309_5a57a1-fb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3309_5a57a1-fb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3309_5a57a1-fb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3309_5a57a1-fb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3309_5f3ae7-72 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:25px;padding-left:10px;}.kadence-column3309_5f3ae7-72 > .kt-inside-inner-col,.kadence-column3309_5f3ae7-72 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3309_5f3ae7-72 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_5f3ae7-72 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_5f3ae7-72 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_5f3ae7-72 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3309_5f3ae7-72{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_5f3ae7-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_5f3ae7-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_5f3ae7-72 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3309_03323c-bb .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-3309_03323c-bb .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:40px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3309_03323c-bb\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3309_7d33ed-6e, .wp-block-kadence-advancedheading.kt-adv-heading3309_7d33ed-6e[data-kb-block=\"kb-adv-heading3309_7d33ed-6e\"]{margin-top:-10px;margin-right:0px;margin-bottom:0px;margin-left:0px;text-align:center;line-height:1em;font-weight:500;font-style:normal;font-family:Inter;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3309_7d33ed-6e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3309_7d33ed-6e[data-kb-block=\"kb-adv-heading3309_7d33ed-6e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3309_7d33ed-6e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3309_7d33ed-6e[data-kb-block=\"kb-adv-heading3309_7d33ed-6e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3309_7d33ed-6e, .wp-block-kadence-advancedheading.kt-adv-heading3309_7d33ed-6e[data-kb-block=\"kb-adv-heading3309_7d33ed-6e\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading3309_7d33ed-6e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3309_7d33ed-6e\">\u00bfPOR QU\u00c9 MERECE LA PENA OPTAR POR NUESTRA AYUDA?<\/h4>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<div class=\"wp-block-columns has-medium-font-size is-layout-flex wp-container-core-columns-is-layout-0fb72d45 wp-block-columns-is-layout-flex\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><style>.kadence-column3309_dfb442-9e > .kt-inside-inner-col{min-height:300px;box-shadow:5px 5px 10px 0px var(--global-palette6, #718096);}.kadence-column3309_dfb442-9e > .kt-inside-inner-col,.kadence-column3309_dfb442-9e > .kt-inside-inner-col:before{border-top-left-radius:19px;border-top-right-radius:19px;border-bottom-right-radius:19px;border-bottom-left-radius:19px;}.kadence-column3309_dfb442-9e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_dfb442-9e > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_dfb442-9e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_dfb442-9e > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3309_dfb442-9e:hover > .kt-inside-inner-col{background-color:var(--global-palette1, #3182CE);background-image:none;}.kadence-column3309_dfb442-9e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3309_dfb442-9e:hover, .kadence-column3309_dfb442-9e:hover h1, .kadence-column3309_dfb442-9e:hover h2, .kadence-column3309_dfb442-9e:hover h3, .kadence-column3309_dfb442-9e:hover h4, .kadence-column3309_dfb442-9e:hover h5, .kadence-column3309_dfb442-9e:hover h6{color:var(--global-palette9, #ffffff);}.kadence-column3309_dfb442-9e{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_dfb442-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_dfb442-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_dfb442-9e kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3309_7a05cc-36 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3309_7a05cc-36 .kt-blocks-info-box-link-wrap{border-top-left-radius:15px;border-top-right-radius:15px;background:rgba(223,223,223,0);padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box3309_7a05cc-36 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3309_7a05cc-36 .kt-info-svg-icon-flip, .kt-info-box3309_7a05cc-36 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3309_7a05cc-36 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-color:var(--global-palette7, #eeeeee);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box3309_7a05cc-36 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box3309_7a05cc-36 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);border-color:var(--global-palette9, #ffffff);}.kt-info-box3309_7a05cc-36 .kt-infobox-textcontent h5.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3309_7a05cc-36 h5.kt-blocks-info-box-title{min-height:27px;}.kt-info-box3309_7a05cc-36 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette8, #F7FAFC);}.wp-block-kadence-infobox.kt-info-box3309_7a05cc-36 .kt-blocks-info-box-text{font-size:var(--global-kb-font-size-md, 1.25rem);letter-spacing:-1px;font-family:var( --global-body-font-family, inherit );font-style:normal;margin-top:24px;margin-right:24px;margin-bottom:24px;margin-left:24px;}.kt-info-box3309_7a05cc-36 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3309_7a05cc-36 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3309_7a05cc-36\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_document kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v8h7v-4h-4v-4h-3zm4 0v3h3l-3-3zm-3 2h1v1h-1v-1zm0 2h1v1h-1v-1zm0 2h4v1h-4v-1z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h5 class=\"kt-blocks-info-box-title\"><strong>Rellenaremos por ti la solicitud de permiso de residencia<\/strong><\/h5><p class=\"kt-blocks-info-box-text\">Reuniremos los datos, completaremos los formularios y nos encargaremos de los anexos.<br\/><br\/><\/p><\/div><\/span><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><style>.kadence-column3309_0cf3c1-b5 > .kt-inside-inner-col,.kadence-column3309_0cf3c1-b5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3309_0cf3c1-b5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_0cf3c1-b5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_0cf3c1-b5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_0cf3c1-b5 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3309_0cf3c1-b5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3309_0cf3c1-b5{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_0cf3c1-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_0cf3c1-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_0cf3c1-b5\"><div class=\"kt-inside-inner-col\"><style>.kadence-column3309_517153-2d > .kt-inside-inner-col{min-height:300px;box-shadow:5px 5px 10px 0px var(--global-palette6, #718096);}.kadence-column3309_517153-2d > .kt-inside-inner-col,.kadence-column3309_517153-2d > .kt-inside-inner-col:before{border-top-left-radius:19px;border-top-right-radius:19px;border-bottom-right-radius:19px;border-bottom-left-radius:19px;}.kadence-column3309_517153-2d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_517153-2d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_517153-2d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_517153-2d > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3309_517153-2d:hover > .kt-inside-inner-col{background-color:var(--global-palette1, #3182CE);background-image:none;}.kadence-column3309_517153-2d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3309_517153-2d:hover, .kadence-column3309_517153-2d:hover h1, .kadence-column3309_517153-2d:hover h2, .kadence-column3309_517153-2d:hover h3, .kadence-column3309_517153-2d:hover h4, .kadence-column3309_517153-2d:hover h5, .kadence-column3309_517153-2d:hover h6{color:var(--global-palette9, #ffffff);}.kadence-column3309_517153-2d{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_517153-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_517153-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_517153-2d kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3309_2359c5-f2 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3309_2359c5-f2 .kt-blocks-info-box-link-wrap{border-top-left-radius:15px;border-top-right-radius:15px;background:rgba(223,223,223,0);padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box3309_2359c5-f2 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3309_2359c5-f2 .kt-info-svg-icon-flip, .kt-info-box3309_2359c5-f2 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3309_2359c5-f2 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-color:var(--global-palette7, #eeeeee);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box3309_2359c5-f2 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box3309_2359c5-f2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);border-color:var(--global-palette9, #ffffff);}.kt-info-box3309_2359c5-f2 .kt-infobox-textcontent h5.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3309_2359c5-f2 h5.kt-blocks-info-box-title{min-height:27px;}.kt-info-box3309_2359c5-f2 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette8, #F7FAFC);}.wp-block-kadence-infobox.kt-info-box3309_2359c5-f2 .kt-blocks-info-box-text{font-size:var(--global-kb-font-size-md, 1.25rem);letter-spacing:-1px;font-family:var( --global-body-font-family, inherit );font-style:normal;margin-top:24px;margin-right:24px;margin-bottom:24px;margin-left:24px;}.kt-info-box3309_2359c5-f2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3309_2359c5-f2 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3309_2359c5-f2\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_file-import kt-info-svg-icon\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M16 288c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h112v-64H16zm336-152V0H152c-13.3 0-24 10.7-24 24v264h127.99v-65.18c0-14.28 17.29-21.41 27.36-11.27l95.7 96.43c6.6 6.65 6.6 17.39 0 24.04l-95.7 96.42c-10.06 10.14-27.36 3.01-27.36-11.27V352H128v136c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H376c-13.2 0-24-10.8-24-24zm153-31L407.1 7c-4.5-4.5-10.6-7-17-7H384v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h5 class=\"kt-blocks-info-box-title\"><strong>Completaremos y presentaremos los documentos en las oficinas competentes<\/strong><\/h5><p class=\"kt-blocks-info-box-text\">Nos ocuparemos de los plazos, presentaremos los escritos y monitorizaremos el estado del expediente.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><style>.kadence-column3309_619fd8-49 > .kt-inside-inner-col{min-height:300px;box-shadow:5px 5px 10px 0px var(--global-palette6, #718096);}.kadence-column3309_619fd8-49 > .kt-inside-inner-col,.kadence-column3309_619fd8-49 > .kt-inside-inner-col:before{border-top-left-radius:19px;border-top-right-radius:19px;border-bottom-right-radius:19px;border-bottom-left-radius:19px;}.kadence-column3309_619fd8-49 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_619fd8-49 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_619fd8-49 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_619fd8-49 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3309_619fd8-49:hover > .kt-inside-inner-col{background-color:var(--global-palette1, #3182CE);background-image:none;}.kadence-column3309_619fd8-49 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3309_619fd8-49:hover, .kadence-column3309_619fd8-49:hover h1, .kadence-column3309_619fd8-49:hover h2, .kadence-column3309_619fd8-49:hover h3, .kadence-column3309_619fd8-49:hover h4, .kadence-column3309_619fd8-49:hover h5, .kadence-column3309_619fd8-49:hover h6{color:var(--global-palette9, #ffffff);}.kadence-column3309_619fd8-49{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_619fd8-49 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_619fd8-49 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_619fd8-49 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3309_626e15-d2 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3309_626e15-d2 .kt-blocks-info-box-link-wrap{border-top-left-radius:15px;border-top-right-radius:15px;background:rgba(223,223,223,0);padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kt-info-box3309_626e15-d2 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3309_626e15-d2 .kt-info-svg-icon-flip, .kt-info-box3309_626e15-d2 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3309_626e15-d2 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-color:var(--global-palette7, #eeeeee);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box3309_626e15-d2 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box3309_626e15-d2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);border-color:var(--global-palette9, #ffffff);}.kt-info-box3309_626e15-d2 .kt-infobox-textcontent h5.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3309_626e15-d2 h5.kt-blocks-info-box-title{min-height:27px;}.kt-info-box3309_626e15-d2 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette8, #F7FAFC);}.wp-block-kadence-infobox.kt-info-box3309_626e15-d2 .kt-blocks-info-box-text{font-size:var(--global-kb-font-size-md, 1.25rem);letter-spacing:-1px;font-family:var( --global-body-font-family, inherit );font-style:normal;margin-top:24px;margin-right:24px;margin-bottom:24px;margin-left:24px;}.kt-info-box3309_626e15-d2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3309_626e15-d2 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3309_626e15-d2\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_user-tie kt-info-svg-icon\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm95.8 32.6L272 480l-32-136 32-56h-96l32 56-32 136-47.8-191.4C56.9 292 0 350.3 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-72.1-56.9-130.4-128.2-133.8z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h5 class=\"kt-blocks-info-box-title\"><strong>Acompa\u00f1amiento durante las visitas a la administraci\u00f3n<\/strong><\/h5><p class=\"kt-blocks-info-box-text\">Garantizamos una representaci\u00f3n completa y profesional durante las visitas a la\u00a0administraci\u00f3n.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column2405_62c8db-b5{max-width:1250px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column2405_62c8db-b5{-webkit-flex:0 1 1250px;flex:0 1 1250px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column2405_62c8db-b5 > .kt-inside-inner-col,.kadence-column2405_62c8db-b5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2405_62c8db-b5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2405_62c8db-b5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2405_62c8db-b5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2405_62c8db-b5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2405_62c8db-b5{position:relative;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column2405_62c8db-b5{-webkit-flex:0 1 1250px;flex:0 1 1250px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kadence-column2405_62c8db-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column2405_62c8db-b5{max-width:1250px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column2405_62c8db-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2405_62c8db-b5\"><div class=\"kt-inside-inner-col\"><style>.kadence-column2405_0c7999-65 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:0px;padding-left:10px;}.kadence-column2405_0c7999-65 > .kt-inside-inner-col,.kadence-column2405_0c7999-65 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2405_0c7999-65 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2405_0c7999-65 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2405_0c7999-65 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2405_0c7999-65 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2405_0c7999-65{position:relative;}@media all and (max-width: 1024px){.kadence-column2405_0c7999-65 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2405_0c7999-65 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2405_0c7999-65 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-2405_2a0ee8-91 .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-2405_2a0ee8-91 .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:40px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-2405_2a0ee8-91\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading2405_cc16ca-af, .wp-block-kadence-advancedheading.kt-adv-heading2405_cc16ca-af[data-kb-block=\"kb-adv-heading2405_cc16ca-af\"]{margin-top:-10px;margin-right:0px;margin-bottom:50px;margin-left:0px;text-align:center;line-height:1em;font-weight:500;font-style:normal;font-family:Inter;}.wp-block-kadence-advancedheading.kt-adv-heading2405_cc16ca-af mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2405_cc16ca-af[data-kb-block=\"kb-adv-heading2405_cc16ca-af\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2405_cc16ca-af img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2405_cc16ca-af[data-kb-block=\"kb-adv-heading2405_cc16ca-af\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading2405_cc16ca-af, .wp-block-kadence-advancedheading.kt-adv-heading2405_cc16ca-af[data-kb-block=\"kb-adv-heading2405_cc16ca-af\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading2405_cc16ca-af wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2405_cc16ca-af\">Lista de precios<\/h4>\n<\/div><\/div>\n\n\n<style>.kt-tabs-id2405_d9b26a-06 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:2px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.wp-block-kadence-tabs .kt-tabs-id2405_d9b26a-06 > .kt-tabs-title-list li{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id2405_d9b26a-06 > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id2405_d9b26a-06 > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id2405_d9b26a-06 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-weight:regular;font-style:normal;border-top-width:0px;border-right-width:0px;border-bottom-width:4px;border-left-width:0px;border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;border-color:var(--global-palette9, #ffffff);color:var(--global-palette4, #2D3748);background:var(--global-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id2405_d9b26a-06 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id2405_d9b26a-06 > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id2405_d9b26a-06 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(--global-palette7, #eeeeee);color:var(--global-palette4, #2D3748);background:var(--global-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id2405_d9b26a-06 > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id2405_d9b26a-06 > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:var(--global-palette1, #3182CE);color:var(--global-palette1, #3182CE);background:var(--global-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id2405_d9b26a-06{max-width:1150px;}@media all and (max-width: 1024px){.kt-tabs-id2405_d9b26a-06 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:2px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-tabs-id2405_d9b26a-06 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:2px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone\"><div class=\"kt-tabs-wrap kt-tabs-id2405_d9b26a-06 kt-tabs-has-3-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-tabs kt-tab-alignment-center \"><ul class=\"kt-tabs-title-list\"><li id=\"tab-kartapobytu\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-kartapobytu\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\">Tarjeta de residencia<\/span><\/a><\/li><li id=\"tab-pracaizatrudnienie\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-pracaizatrudnienie\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\">Trabajo y empleo<\/span><\/a><\/li><li id=\"tab-inne\" class=\"kt-title-item kt-title-item-3 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-inne\" data-tab=\"3\" class=\"kt-tab-title kt-tab-title-3 \"><span class=\"kt-title-text\">Otros<\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab2405_ebbfc9-82\"><div class=\"kt-tab-inner-content-inner\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-4c3d31c9 wp-block-columns-is-layout-flex\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#efefef\"><style>.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col{display:flex;}.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);}.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col,.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col{row-gap:var(--global-kb-gap-none, 0rem );column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column2405_fbb3dc-1d{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2405_fbb3dc-1d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2405_fbb3dc-1d{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column2405_fbb3dc-1d{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2405_fbb3dc-1d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column2405_fbb3dc-1d{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2405_fbb3dc-1d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column2405_fbb3dc-1d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2405_fbb3dc-1d kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\">\n<h4 class=\"wp-block-heading has-text-align-center\">Est\u00e1ndar<\/h4>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center has-theme-palette-1-color has-text-color has-link-color wp-elements-2\"><strong>599 z\u0142<\/strong><\/h1>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-center\">por 1 persona<\/h6>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-2405_f45449-ea .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-2405_f45449-ea .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette6, #718096);width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-2405_f45449-ea\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40);font-size:16px\">Consultas con explicaci\u00f3n de la situaci\u00f3n completa y propuesta de la mejor soluci\u00f3n<br\/><br\/>Relleno correcto de la solicitud y de los documentos adicionales<br\/><br\/>Explicaci\u00f3n de todo el proceso de solicitud, as\u00ed como de los pasos siguientes<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns2405_08c295-b6{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:flex-start;}.kt-btns2405_08c295-b6 .kt-button{font-weight:normal;font-style:normal;}.kt-btns2405_08c295-b6 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns2405_08c295-b6 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns2405_08c295-b6 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns2405_08c295-b6 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns2405_08c295-b6 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns2405_08c295-b6 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns2405_08c295-b6 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns2405_08c295-b6 popmake-5212\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn2405_2fb494-c5.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn2405_2fb494-c5.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);text-transform:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);margin-right:var(--global-kb-spacing-xs, 1rem);margin-left:var(--global-kb-spacing-xs, 1rem);}.wp-block-kadence-advancedbtn .kb-btn2405_2fb494-c5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn2405_2fb494-c5.kb-button:focus{color:var(--global-palette1, #3182CE);background:#ffffff;border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn2405_2fb494-c5.kb-button{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn2405_2fb494-c5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn2405_2fb494-c5.kb-button:focus{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn2405_2fb494-c5.kb-button{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advancedbtn .kb-btn2405_2fb494-c5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn2405_2fb494-c5.kb-button:focus{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}<\/style><span class=\"kb-button kt-button button kb-btn2405_2fb494-c5 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Quiero este paquete<\/span><\/span><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><style>.kadence-column2405_e53c5a-b3 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);}.kadence-column2405_e53c5a-b3 > .kt-inside-inner-col,.kadence-column2405_e53c5a-b3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2405_e53c5a-b3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2405_e53c5a-b3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2405_e53c5a-b3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2405_e53c5a-b3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2405_e53c5a-b3{position:relative;}@media all and (max-width: 1024px){.kadence-column2405_e53c5a-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2405_e53c5a-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2405_e53c5a-b3\"><div class=\"kt-inside-inner-col\">\n<h4 class=\"wp-block-heading has-text-align-center\">Premium<\/h4>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center has-theme-palette-1-color has-text-color has-link-color wp-elements-3\"><strong>1400* z\u0142<\/strong><\/h1>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-center\">por 1 persona<\/h6>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-2405_2a9c5e-d5 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-2405_2a9c5e-d5 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette6, #718096);width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-2405_2a9c5e-d5\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40);font-size:16px\">Consultas con explicaci\u00f3n de la situaci\u00f3n completa y propuesta de la mejor soluci\u00f3n<br\/><br\/>Relleno correcto de la solicitud y de los documentos adicionales<br\/><br\/>Explicaci\u00f3n de todo el proceso de solicitud, as\u00ed como de los pasos siguientes<br\/><br\/>Representaci\u00f3n profesional de un coordinador\/int\u00e9rprete, responsable de tu caso hasta la emisi\u00f3n de la decisi\u00f3n<br\/><br\/><strong>Seguimiento completo del caso<\/strong>: preparaci\u00f3n de cartas, recursos y respuestas a todos los requerimientos por parte de la autoridad<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns2405_4a0318-b1{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns2405_4a0318-b1 .kt-button{font-weight:normal;font-style:normal;}.kt-btns2405_4a0318-b1 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns2405_4a0318-b1 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns2405_4a0318-b1 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns2405_4a0318-b1 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns2405_4a0318-b1 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns2405_4a0318-b1 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns2405_4a0318-b1 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns2405_4a0318-b1 popmake-5212\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn2405_fbd4b8-07.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn2405_fbd4b8-07.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);text-transform:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);margin-right:var(--global-kb-spacing-xs, 1rem);margin-left:var(--global-kb-spacing-xs, 1rem);}.wp-block-kadence-advancedbtn .kb-btn2405_fbd4b8-07.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn2405_fbd4b8-07.kb-button:focus{color:var(--global-palette1, #3182CE);background:#ffffff;border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn2405_fbd4b8-07.kb-button{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn2405_fbd4b8-07.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn2405_fbd4b8-07.kb-button:focus{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn2405_fbd4b8-07.kb-button{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advancedbtn .kb-btn2405_fbd4b8-07.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn2405_fbd4b8-07.kb-button:focus{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}<\/style><span class=\"kb-button kt-button button kb-btn2405_fbd4b8-07 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Quiero este paquete<\/span><\/span><\/div>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40);font-size:11px\">*La tarifa puede variar para cada cliente debido a la complejidad del caso. En caso de cooperaci\u00f3n continua, los precios se fijan de forma individual.<\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#efefef;padding-right:0;padding-left:0\"><style>.kadence-column2405_aaf45f-13 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);}.kadence-column2405_aaf45f-13 > .kt-inside-inner-col,.kadence-column2405_aaf45f-13 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2405_aaf45f-13 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2405_aaf45f-13 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2405_aaf45f-13 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2405_aaf45f-13 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2405_aaf45f-13{position:relative;}@media all and (max-width: 1024px){.kadence-column2405_aaf45f-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2405_aaf45f-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2405_aaf45f-13\"><div class=\"kt-inside-inner-col\">\n<h4 class=\"wp-block-heading has-text-align-center\">Familia 2+1<\/h4>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center has-theme-palette-1-color has-text-color has-link-color wp-elements-4\" style=\"padding-top:0;padding-bottom:0\"><strong>3300 z\u0142<\/strong><\/h1>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-center\">por el caso<\/h6>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-2405_a71e01-d1 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-2405_a71e01-d1 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette6, #718096);width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-2405_a71e01-d1\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40);font-size:16px\">Consultas con explicaci\u00f3n de la situaci\u00f3n completa y propuesta de la mejor soluci\u00f3n<br\/><br\/>Relleno correcto de la solicitud y de los documentos adicionales<br\/><br\/>Explicaci\u00f3n de todo el proceso de solicitud, as\u00ed como de los pasos siguientes<br\/><br\/>Representaci\u00f3n profesional de un coordinador\/int\u00e9rprete, responsable de tu caso hasta la emisi\u00f3n de la decisi\u00f3n<br\/><br\/><strong>Seguimiento completo del caso<\/strong>: preparaci\u00f3n de cartas, recursos y respuestas a todos los requerimientos por parte de la autoridad<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns2405_5557f3-46{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns2405_5557f3-46 .kt-button{font-weight:normal;font-style:normal;}.kt-btns2405_5557f3-46 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns2405_5557f3-46 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns2405_5557f3-46 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns2405_5557f3-46 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns2405_5557f3-46 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns2405_5557f3-46 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns2405_5557f3-46 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns2405_5557f3-46 popmake-5212\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn2405_e2f172-09.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn2405_e2f172-09.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);text-transform:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);margin-right:var(--global-kb-spacing-xs, 1rem);margin-left:var(--global-kb-spacing-xs, 1rem);}.wp-block-kadence-advancedbtn .kb-btn2405_e2f172-09.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn2405_e2f172-09.kb-button:focus{color:var(--global-palette1, #3182CE);background:#ffffff;border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn2405_e2f172-09.kb-button{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn2405_e2f172-09.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn2405_e2f172-09.kb-button:focus{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn2405_e2f172-09.kb-button{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advancedbtn .kb-btn2405_e2f172-09.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn2405_e2f172-09.kb-button:focus{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}<\/style><span class=\"kb-button kt-button button kb-btn2405_e2f172-09 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Quiero este paquete<\/span><\/span><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab2405_d00539-50\"><div class=\"kt-tab-inner-content-inner\">\n<figure class=\"wp-block-table alignwide is-style-stripes\" style=\"padding-right:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40);font-size:16px\"><table><tbody><tr><td><strong>01<\/strong><\/td><td>Notificaci\u00f3n sobre encomendar el desempe\u00f1o de trabajo a un ciudadano de Ucrania*<\/td><td class=\"has-text-align-right\" data-align=\"right\"><strong>250 z\u0142<\/strong><\/td><\/tr><tr><td><strong>02<\/strong><\/td><td>Declaraci\u00f3n sobre encomendar el desempe\u00f1o de trabajo a un extranjero<\/td><td class=\"has-text-align-right\" data-align=\"right\">desde <strong>550 z\u0142*<\/strong><\/td><\/tr><tr><td><strong>03<\/strong><\/td><td>Permiso de trabajo de cualquier tipo <\/td><td class=\"has-text-align-right\" data-align=\"right\">desde <strong>550 z\u0142<\/strong>*<\/td><\/tr><tr><td><strong>04<\/strong><\/td><td>Solicitud unificada (permiso de residencia temporal y de trabajo)<\/td><td class=\"has-text-align-right\" data-align=\"right\">desde <strong>1400 z\u0142<\/strong>*<\/td><\/tr><tr><td><strong>05<\/strong><\/td><td>Informaci\u00f3n del starosta<\/td><td class=\"has-text-align-right\" data-align=\"right\"><strong>200 z\u0142<\/strong><\/td><\/tr><tr><td><strong>06<\/strong><\/td><td>Preparaci\u00f3n de la documentaci\u00f3n para la contrataci\u00f3n legal de un extranjero en el territorio de la Rep\u00fablica de Polonia<br\/>(preparaci\u00f3n de la solicitud de residencia y trabajo + preparaci\u00f3n de la documentaci\u00f3n de la oferta de trabajo para la emisi\u00f3n de la opini\u00f3n del starosta)<\/td><td class=\"has-text-align-right\" data-align=\"right\">desde <strong>1400 z\u0142<\/strong>*<\/td><\/tr><tr><td><strong>07<\/strong><\/td><td>Redacci\u00f3n del plan de negocios<\/td><td class=\"has-text-align-right\" data-align=\"right\">desde <strong>500 z\u0142*<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">* La tarifa puede variar para cada cliente debido a la complejidad del caso. En caso de cooperaci\u00f3n continua, los precios se fijan de forma individual.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-3 kt-inner-tab2405_721574-00\"><div class=\"kt-tab-inner-content-inner\">\n<figure class=\"wp-block-table alignwide is-style-stripes\" style=\"padding-right:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40);font-size:16px\"><table><tbody><tr><th>01<\/th><td>Ayuda para obtener el n\u00famero PESEL o empadronamiento<\/td><td class=\"has-text-align-right\" data-align=\"right\">desde <strong>250 z\u0142<\/strong>*<\/td><\/tr><tr><th>02<\/th><td>Consultas para extranjeros y empleadores presenciales \/ en l\u00ednea<\/td><td class=\"has-text-align-right\" data-align=\"right\"><strong>300 z\u0142<\/strong><\/td><\/tr><tr><th>03<\/th><td>Asistencia en la oficina<\/td><td class=\"has-text-align-right\" data-align=\"right\"><strong>350 z\u0142<\/strong><\/td><\/tr><tr><th>04<\/th><td>Revisi\u00f3n del conjunto de documentos para presentar en la oficina<\/td><td class=\"has-text-align-right\" data-align=\"right\"><strong>200 z\u0142<\/strong><\/td><\/tr><tr><th>05<\/th><td>Reservar una cita en la oficina o presentar los documentos<\/td><td class=\"has-text-align-right\" data-align=\"right\"><strong>250 z\u0142<\/strong><\/td><\/tr><tr><th>06<\/th><td>Recursos contra decisiones, apoyo durante inspecciones<\/td><td class=\"has-text-align-right\" data-align=\"right\">desde <strong>550 z\u0142<\/strong>*<\/td><\/tr><tr><td><strong>07<\/strong><\/td><td>Ayuda para obtener el permiso de conducir<\/td><td class=\"has-text-align-right\" data-align=\"right\">desde <strong>350 z\u0142*<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">* La tarifa puede variar para cada cliente debido a la complejidad del caso. En caso de cooperaci\u00f3n continua, los precios se fijan de forma individual.<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3309_ad2f04-03 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:0px;padding-left:10px;}.kadence-column3309_ad2f04-03 > .kt-inside-inner-col,.kadence-column3309_ad2f04-03 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3309_ad2f04-03 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3309_ad2f04-03 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3309_ad2f04-03 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3309_ad2f04-03 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3309_ad2f04-03{position:relative;}@media all and (max-width: 1024px){.kadence-column3309_ad2f04-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3309_ad2f04-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3309_ad2f04-03 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3309_5de433-a1 .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-3309_5de433-a1 .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:40px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3309_5de433-a1\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3309_21a86c-2a, .wp-block-kadence-advancedheading.kt-adv-heading3309_21a86c-2a[data-kb-block=\"kb-adv-heading3309_21a86c-2a\"]{margin-top:-10px;margin-right:0px;margin-bottom:0px;margin-left:0px;text-align:center;line-height:1em;font-weight:500;font-style:normal;font-family:Inter;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3309_21a86c-2a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3309_21a86c-2a[data-kb-block=\"kb-adv-heading3309_21a86c-2a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3309_21a86c-2a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3309_21a86c-2a[data-kb-block=\"kb-adv-heading3309_21a86c-2a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3309_21a86c-2a, .wp-block-kadence-advancedheading.kt-adv-heading3309_21a86c-2a[data-kb-block=\"kb-adv-heading3309_21a86c-2a\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading3309_21a86c-2a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3309_21a86c-2a\">CONTACTO<\/h4>\n<\/div><\/div>\n<\/div><\/div>\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id2401_341dd5-be{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id2401_341dd5-be > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2401_341dd5-be > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2401_341dd5-be > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:1250px;margin-left:auto;margin-right:auto;padding-top:51px;padding-right:0px;padding-bottom:22px;padding-left:0px;grid-template-columns:minmax(0, calc(40% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(60% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id2401_341dd5-be{background-image:url('https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2024\/01\/02.png');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id2401_341dd5-be > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2401_341dd5-be > .kt-row-column-wrap{padding-top:80px;padding-right:20px;padding-bottom:80px;padding-left:20px;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id2401_341dd5-be > .kt-row-column-wrap{padding-top:60px;padding-right:20px;padding-bottom:60px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2401_341dd5-be alignnone has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column2401_9aa931-1a > .kt-inside-inner-col{display:flex;}.kadence-column2401_9aa931-1a > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column2401_9aa931-1a > .kt-inside-inner-col,.kadence-column2401_9aa931-1a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2401_9aa931-1a > .kt-inside-inner-col{row-gap:0px;column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2401_9aa931-1a > .kt-inside-inner-col{flex-direction:column;}.kadence-column2401_9aa931-1a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2401_9aa931-1a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2401_9aa931-1a{position:relative;}@media all and (max-width: 1024px){.kadence-column2401_9aa931-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2401_9aa931-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2401_9aa931-1a inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kadence-column2401_06bf07-46 > .kt-inside-inner-col{display:flex;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col,.kadence-column2401_06bf07-46 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col{row-gap:0px;column-gap:var(--global-kb-gap-none, 0rem );}.kadence-column2401_06bf07-46 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;flex-wrap:nowrap;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col > *, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2401_06bf07-46 a{color:var(--global-palette9, #ffffff);}.kadence-column2401_06bf07-46 a:hover{color:var(--global-palette2, #2B6CB0);}.kadence-column2401_06bf07-46{position:relative;}@media all and (max-width: 1024px){.kadence-column2401_06bf07-46 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;flex-wrap:nowrap;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column2401_06bf07-46 > .kt-inside-inner-col > *, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column2401_06bf07-46 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;flex-wrap:nowrap;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col > *, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2401_06bf07-46 kb-section-dir-horizontal inner-column-1\"><div class=\"kt-inside-inner-col\"><style id=\"wpforms-css-vars-2331-block-ed363ec0-d2eb-4ec5-a74c-166069c05f95\">\n\t\t\t\t#wpforms-2331.wpforms-block-ed363ec0-d2eb-4ec5-a74c-166069c05f95 {\n\t\t\t\t--wpforms-label-color: var(--global-palette9);\n--wpforms-label-sublabel-color: var(--global-palette9);\n--wpforms-field-text-color: var(--global-palette8);\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-ed363ec0-d2eb-4ec5-a74c-166069c05f95 wpforms-render-modern\" id=\"wpforms-2331\"><form id=\"wpforms-form-2331\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"2331\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/3873\" data-token=\"47adf575e95353a3028b5175a5d0e6eb\" data-token-time=\"1788357815\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-2331-field_2-container\" class=\"wpforms-field wpforms-field-name form-name\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-2331-field_2\">Nombre <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2331-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-2331-field_2-error\" required><\/div><div id=\"wpforms-2331-field_3-container\" class=\"wpforms-field wpforms-field-email form-email\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-2331-field_3\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-2331-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-2331-field_3-error\" required><\/div>\t\t<div id=\"wpforms-2331-field_1-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"1\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-2331-field_1\" >en Marketing a<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-2331-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-2331-field_5-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-2331-field_5\">\u00bfC\u00f3mo podemos ayudarte? Te invitamos a ponerte en contacto <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-2331-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" aria-errormessage=\"wpforms-2331-field_5-error\" required><\/textarea><\/div><div id=\"wpforms-2331-field_4-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"4\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Consentimientos <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-2331-field_4\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-2331-field_4_1\" name=\"wpforms[fields][4][]\" value=\"Autorizo el tratamiento de mis datos personales con el fin de gestionar mi consulta de acuerdo con\" aria-errormessage=\"wpforms-2331-field_4_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2331-field_4_1\">Autorizo el tratamiento de mis datos personales con el fin de gestionar mi consulta de acuerdo con<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-2331-field_7-container\" class=\"wpforms-field wpforms-field-text hide-field marketing-data-field\" data-field-id=\"7\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2331-field_7\" aria-hidden=\"false\">Marketing<\/label><input type=\"text\" id=\"wpforms-2331-field_7\" class=\"wpforms-field-large\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-2331-field_7-error\" ><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-2331-field_1-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-2331-field_1-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-2331-field_1-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-invisible\" ><div class=\"g-recaptcha\" data-sitekey=\"6LdKGqUpAAAAAOgcVz-d4IbEfW38vGIuyF1QS_MP\" data-size=\"invisible\"><\/div><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"2331\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/pages\/3873\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-2331\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/old.pcr-legal.pl\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column2401_20a729-ee > .kt-inside-inner-col{display:flex;}.kadence-column2401_20a729-ee > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kadence-column2401_20a729-ee > .kt-inside-inner-col,.kadence-column2401_20a729-ee > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2401_20a729-ee > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column2401_20a729-ee > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column2401_20a729-ee{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column2401_20a729-ee > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2401_20a729-ee{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column2401_20a729-ee{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column2401_20a729-ee{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2401_20a729-ee\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-theme-palette-9-color has-text-color has-link-color has-large-font-size wp-elements-5 wp-block-paragraph\" style=\"text-transform:none\">\u00bfTienes preguntas? \u00bfQuieres utilizar el servicio?<\/p>\n\n\n\n<p class=\"has-theme-palette-9-color has-text-color has-link-color wp-elements-6 wp-block-paragraph\">Escr\u00edbenos y un especialista se pondr\u00e1 en contacto contigo lo antes posible<\/p>\n\n\n<style>.kadence-column2401_094173-1c > .kt-inside-inner-col,.kadence-column2401_094173-1c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2401_094173-1c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2401_094173-1c > .kt-inside-inner-col{flex-direction:column;}.kadence-column2401_094173-1c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2401_094173-1c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2401_094173-1c{position:relative;}@media all and (max-width: 1024px){.kadence-column2401_094173-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2401_094173-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2401_094173-1c\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-theme-palette-2-color has-theme-palette-9-background-color has-text-color has-background has-link-color has-custom-font-size wp-element-button\" href=\"tel:+48572868879\" style=\"padding-top:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--50);font-size:16px\">Ll\u00e1manos<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-theme-palette-2-color has-theme-palette-9-background-color has-text-color has-background has-link-color has-custom-font-size wp-element-button\" href=\"https:\/\/www.google.com\/maps\/place\/Polskie+Centrum+Rezydencji\/@54.3400247,18.6568298,17z\/data=!4m6!3m5!1s0x46fd7383d87233ab:0xe51864d1f8dfb18b!8m2!3d54.3400216!4d18.6594047!16s%2Fg%2F11vk9g8_26?entry=ttu\" style=\"padding-top:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--50);font-size:16px\" target=\"_blank\" rel=\"noopener\">Encuentra nuestra oficina<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Permiso de residencia Permiso de residencia (tarjeta de residencia) es un documento que permite a los extranjeros residir legalmente en Polonia por un per\u00edodo determinado, incluso hasta tres a\u00f1os. Adem\u00e1s, permite viajar libremente dentro del espacio Schengen sin necesidad de obtener visados adicionales. \u00bfQUI\u00c9N PUEDE SOLICITAR EL PERMISO DE RESIDENCIA? Puede solicitar el permiso de&#8230;<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_kadence_starter_templates_imported_post":false,"_swpsp_post_exclude":false,"_kad_post_transparent":"enable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-3873","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/pages\/3873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/comments?post=3873"}],"version-history":[{"count":11,"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/pages\/3873\/revisions"}],"predecessor-version":[{"id":4503,"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/pages\/3873\/revisions\/4503"}],"wp:attachment":[{"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/media?parent=3873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}