{"id":3980,"date":"2025-07-29T12:58:02","date_gmt":"2025-07-29T10:58:02","guid":{"rendered":"https:\/\/pcr-legal.pl\/asesoramiento-en-la-contratacion-de-extranjeros\/"},"modified":"2025-11-12T12:54:46","modified_gmt":"2025-11-12T11:54:46","slug":"asesoramiento-en-la-contratacion-de-extranjeros","status":"publish","type":"page","link":"https:\/\/old.pcr-legal.pl\/es\/asesoramiento-en-la-contratacion-de-extranjeros\/","title":{"rendered":"Asesoramiento en la contrataci\u00f3n de extranjeros"},"content":{"rendered":"<style>.kadence-column3383_c52401-bb > .kt-inside-inner-col,.kadence-column3383_c52401-bb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3383_c52401-bb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_c52401-bb > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_c52401-bb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_c52401-bb > .kt-inside-inner-col{background-color:#ffffff;background-image:url('https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2024\/01\/05.png');background-size:cover;background-position:48% 52%;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column3383_c52401-bb > .kt-inside-inner-col:before{opacity:0.52;background-color:var(--global-palette4, #2D3748);}.kadence-column3383_c52401-bb{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_c52401-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_c52401-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_c52401-bb kvs-sm-false kb-section-has-overlay\"><div class=\"kt-inside-inner-col\">\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center has-theme-palette-9-color has-text-color has-link-color wp-elements-1\" style=\"font-size:86px;text-transform:none\">Asesoramiento en la contrataci\u00f3n de extranjeros<\/h1>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n<style>.kadence-column3383_c71bd0-50 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-3xl, 6.5rem);}.kadence-column3383_c71bd0-50 > .kt-inside-inner-col,.kadence-column3383_c71bd0-50 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3383_c71bd0-50 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_c71bd0-50 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_c71bd0-50 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_c71bd0-50 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3383_c71bd0-50{text-align:left;}.kadence-column3383_c71bd0-50{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_c71bd0-50 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_c71bd0-50 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_c71bd0-50\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full has-custom-border\"><img data-dominant-color=\"656160\" data-has-transparency=\"false\" loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" src=\"https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2025\/09\/pexels-cottonbro-6567872-edited-1-scaled.avif\" alt=\"\" class=\"wp-image-3573 not-transparent\" style=\"--dominant-color: #656160; border-radius:20px\" srcset=\"https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2025\/09\/pexels-cottonbro-6567872-edited-1-scaled.avif 2560w, https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2025\/09\/pexels-cottonbro-6567872-edited-1-300x169.avif 300w, https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2025\/09\/pexels-cottonbro-6567872-edited-1-1024x576.avif 1024w, https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2025\/09\/pexels-cottonbro-6567872-edited-1-768x432.avif 768w, https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2025\/09\/pexels-cottonbro-6567872-edited-1-1536x864.avif 1536w, https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2025\/09\/pexels-cottonbro-6567872-edited-1-2048x1152.avif 2048w\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">La contrataci\u00f3n de trabajadores del extranjero es un proceso complejo y laborioso que requiere conocer la normativa polaca de derecho laboral y la legalizaci\u00f3n del empleo. Nuestro servicio de <strong>Asesoramiento en la Contrataci\u00f3n de Extranjeros<\/strong> es un apoyo que permite evitar errores, agilizar los tr\u00e1mites y proteger plenamente los intereses de tu empresa.<\/p>\n<\/div>\n<\/div>\n\n\n<style>.kadence-column3383_6c16a7-46 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:25px;padding-left:10px;}.kadence-column3383_6c16a7-46 > .kt-inside-inner-col,.kadence-column3383_6c16a7-46 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3383_6c16a7-46 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_6c16a7-46 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_6c16a7-46 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_6c16a7-46 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3383_6c16a7-46{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_6c16a7-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_6c16a7-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_6c16a7-46 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3383_402694-b8 .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-3383_402694-b8 .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:40px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3383_402694-b8\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3383_d4a3c5-de, .wp-block-kadence-advancedheading.kt-adv-heading3383_d4a3c5-de[data-kb-block=\"kb-adv-heading3383_d4a3c5-de\"]{margin-top:-10px;margin-right:0px;margin-bottom:0px;margin-left:0px;text-align:center;line-height:1em;font-weight:500;font-style:normal;font-family:Inter;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3383_d4a3c5-de mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3383_d4a3c5-de[data-kb-block=\"kb-adv-heading3383_d4a3c5-de\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3383_d4a3c5-de img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3383_d4a3c5-de[data-kb-block=\"kb-adv-heading3383_d4a3c5-de\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3383_d4a3c5-de, .wp-block-kadence-advancedheading.kt-adv-heading3383_d4a3c5-de[data-kb-block=\"kb-adv-heading3383_d4a3c5-de\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading3383_d4a3c5-de wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3383_d4a3c5-de\">\u00bfC\u00d3MO CONTRATAR A UN EXTRANJERO EN POLONIA?<\/h4>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los ciudadanos de terceros pa\u00edses pueden asumir un empleo legal en Polonia sobre la base de dos documentos principales:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Permiso de trabajo<\/strong><em> &#8211; <\/em>el documento clave que legaliza la contrataci\u00f3n de extranjeros. Lo expide el voivoda y permite al extranjero desempe\u00f1ar trabajo de forma legal en Polonia. Es imprescindible cuando una persona de fuera de la Uni\u00f3n Europea o del Espacio Econ\u00f3mico Europeo quiere trabajar en Polonia. Sin este documento, el trabajo en Polonia puede considerarse ilegal, lo que puede acarrear consecuencias jur\u00eddicas tanto para el trabajador como para el empleador.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Declaraci\u00f3n de encomienda de trabajo a un extranjero<\/strong> \u2013 un procedimiento de contrataci\u00f3n r\u00e1pido que se aplica a los ciudadanos de determinados pa\u00edses, como Ucrania, Bielorrusia, Armenia, Georgia y Moldavia.<\/li>\n<\/ul>\n\n\n<style>.kadence-column3383_9834e2-5c > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:25px;padding-left:10px;}.kadence-column3383_9834e2-5c > .kt-inside-inner-col,.kadence-column3383_9834e2-5c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3383_9834e2-5c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_9834e2-5c > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_9834e2-5c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_9834e2-5c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3383_9834e2-5c{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_9834e2-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_9834e2-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_9834e2-5c inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3383_3f150c-44 .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-3383_3f150c-44 .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:40px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3383_3f150c-44\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3383_fd15ec-98, .wp-block-kadence-advancedheading.kt-adv-heading3383_fd15ec-98[data-kb-block=\"kb-adv-heading3383_fd15ec-98\"]{margin-top:-10px;margin-right:0px;margin-bottom:0px;margin-left:0px;text-align:center;line-height:1em;font-weight:500;font-style:normal;font-family:Inter;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3383_fd15ec-98 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3383_fd15ec-98[data-kb-block=\"kb-adv-heading3383_fd15ec-98\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3383_fd15ec-98 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3383_fd15ec-98[data-kb-block=\"kb-adv-heading3383_fd15ec-98\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3383_fd15ec-98, .wp-block-kadence-advancedheading.kt-adv-heading3383_fd15ec-98[data-kb-block=\"kb-adv-heading3383_fd15ec-98\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading3383_fd15ec-98 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3383_fd15ec-98\">\u00bfA QU\u00c9 CONVIENE PRESTAR ATENCI\u00d3N?<\/h4>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Cada procedimiento de contrataci\u00f3n de un extranjero exige asegurarse de que el trabajador posee la documentaci\u00f3n adecuada para extranjeros, conforme a la legislaci\u00f3n polaca. La legalizaci\u00f3n del trabajo en Polonia requiere no solo permisos v\u00e1lidos, sino tambi\u00e9n el cumplimiento de los requisitos relativos a las condiciones de empleo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estancia legal del extranjero: visado, tarjeta de residencia o exenci\u00f3n de visado.<\/li>\n\n\n\n<li>Los documentos relativos al empleo cumplen los requisitos del derecho laboral polaco.<\/li>\n\n\n\n<li>Las condiciones de empleo (p. ej., tipo de contrato, remuneraci\u00f3n) cumplen la normativa para evitar posibles sanciones.<\/li>\n<\/ul>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3383_5db54a-85{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id3383_5db54a-85 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3383_5db54a-85 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3383_5db54a-85 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:1300px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3383_5db54a-85 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3383_5db54a-85 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3383_5db54a-85 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3383_5db54a-85 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3383_c58441-93 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:25px;padding-left:10px;}.kadence-column3383_c58441-93 > .kt-inside-inner-col,.kadence-column3383_c58441-93 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3383_c58441-93 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_c58441-93 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_c58441-93 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_c58441-93 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3383_c58441-93{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_c58441-93 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_c58441-93 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_c58441-93 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3383_f8eb13-2c .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-3383_f8eb13-2c .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:40px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3383_f8eb13-2c\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3383_679ad4-df, .wp-block-kadence-advancedheading.kt-adv-heading3383_679ad4-df[data-kb-block=\"kb-adv-heading3383_679ad4-df\"]{margin-top:-10px;margin-right:0px;margin-bottom:0px;margin-left:0px;text-align:center;line-height:1em;font-weight:500;font-style:normal;font-family:Inter;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3383_679ad4-df mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3383_679ad4-df[data-kb-block=\"kb-adv-heading3383_679ad4-df\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3383_679ad4-df img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3383_679ad4-df[data-kb-block=\"kb-adv-heading3383_679ad4-df\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3383_679ad4-df, .wp-block-kadence-advancedheading.kt-adv-heading3383_679ad4-df[data-kb-block=\"kb-adv-heading3383_679ad4-df\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading3383_679ad4-df wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3383_679ad4-df\">NUESTROS SERVICIOS EN MATERIA DE CONTRATACI\u00d3N DE EXTRANJEROS<\/h4>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\">Nuestra empresa ofrece apoyo en cada etapa del proceso de contrataci\u00f3n de extranjeros:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Apoyo en las inspecciones de legalidad del empleo<\/strong> \u2013 asesoramos sobre c\u00f3mo prepararse para una inspecci\u00f3n por parte de la Guardia Fronteriza o de la Inspecci\u00f3n Estatal de Trabajo.<\/li>\n\n\n\n<li><strong>Asesoramiento en la elecci\u00f3n del procedimiento adecuado<\/strong> \u2013 te indicaremos si, en tu situaci\u00f3n, es m\u00e1s conveniente un permiso de trabajo o una declaraci\u00f3n.<\/li>\n\n\n\n<li><strong>Elaboraci\u00f3n y verificaci\u00f3n de documentos<\/strong> \u2013 nos encargamos de preparar la documentaci\u00f3n completa para extranjeros, incluidas las solicitudes, las declaraciones y los permisos.<\/li>\n\n\n\n<li><strong>Registro de declaraciones en las oficinas de empleo<\/strong> \u2013 nos ocupamos de las formalidades, ahorrando tu tiempo y eliminando el riesgo de errores.<\/li>\n\n\n\n<li><strong>Consultor\u00edas en materia de legalizaci\u00f3n de la estancia<\/strong> \u2013 verificaremos si el candidato posee el estatus de residencia adecuado y ayudaremos a los extranjeros a obtener los documentos necesarios para que puedan incorporarse a trabajar en tu empresa.<\/li>\n<\/ul>\n\n\n<style>.kadence-column3383_cb4e4a-86 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:25px;padding-left:10px;}.kadence-column3383_cb4e4a-86 > .kt-inside-inner-col,.kadence-column3383_cb4e4a-86 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3383_cb4e4a-86 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_cb4e4a-86 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_cb4e4a-86 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_cb4e4a-86 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3383_cb4e4a-86{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_cb4e4a-86 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_cb4e4a-86 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_cb4e4a-86 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3383_3cfd82-86{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id3383_3cfd82-86 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3383_3cfd82-86 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3383_3cfd82-86 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:1300px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3383_3cfd82-86 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3383_3cfd82-86 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3383_3cfd82-86 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3383_3cfd82-86 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3383_89af35-b4 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:25px;padding-left:10px;}.kadence-column3383_89af35-b4 > .kt-inside-inner-col,.kadence-column3383_89af35-b4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3383_89af35-b4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_89af35-b4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_89af35-b4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_89af35-b4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3383_89af35-b4{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_89af35-b4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_89af35-b4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_89af35-b4 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3383_49ff44-e6 .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-3383_49ff44-e6 .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:40px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3383_49ff44-e6\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3383_d8fa96-98, .wp-block-kadence-advancedheading.kt-adv-heading3383_d8fa96-98[data-kb-block=\"kb-adv-heading3383_d8fa96-98\"]{margin-top:-10px;margin-right:0px;margin-bottom:0px;margin-left:0px;text-align:center;line-height:1em;font-weight:500;font-style:normal;font-family:Inter;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3383_d8fa96-98 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3383_d8fa96-98[data-kb-block=\"kb-adv-heading3383_d8fa96-98\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3383_d8fa96-98 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3383_d8fa96-98[data-kb-block=\"kb-adv-heading3383_d8fa96-98\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3383_d8fa96-98, .wp-block-kadence-advancedheading.kt-adv-heading3383_d8fa96-98[data-kb-block=\"kb-adv-heading3383_d8fa96-98\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading3383_d8fa96-98 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3383_d8fa96-98\">\u00bfPOR QU\u00c9 CONVIENE OPTAR POR NUESTRA AYUDA?<\/h4>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<div class=\"wp-block-columns has-medium-font-size is-layout-flex wp-container-core-columns-is-layout-0fb72d45 wp-block-columns-is-layout-flex\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><style>.kadence-column3383_3d234b-bb > .kt-inside-inner-col{min-height:300px;box-shadow:5px 5px 10px 0px var(--global-palette6, #718096);}.kadence-column3383_3d234b-bb > .kt-inside-inner-col,.kadence-column3383_3d234b-bb > .kt-inside-inner-col:before{border-top-left-radius:19px;border-top-right-radius:19px;border-bottom-right-radius:19px;border-bottom-left-radius:19px;}.kadence-column3383_3d234b-bb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_3d234b-bb > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_3d234b-bb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_3d234b-bb > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3383_3d234b-bb:hover > .kt-inside-inner-col{background-color:var(--global-palette1, #3182CE);background-image:none;}.kadence-column3383_3d234b-bb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3383_3d234b-bb:hover, .kadence-column3383_3d234b-bb:hover h1, .kadence-column3383_3d234b-bb:hover h2, .kadence-column3383_3d234b-bb:hover h3, .kadence-column3383_3d234b-bb:hover h4, .kadence-column3383_3d234b-bb:hover h5, .kadence-column3383_3d234b-bb:hover h6{color:var(--global-palette9, #ffffff);}.kadence-column3383_3d234b-bb{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_3d234b-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_3d234b-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_3d234b-bb kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3383_612a39-98 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3383_612a39-98 .kt-blocks-info-box-link-wrap{border-top-left-radius:15px;border-top-right-radius:15px;background:rgba(223,223,223,0);padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);}.kt-info-box3383_612a39-98 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3383_612a39-98 .kt-info-svg-icon-flip, .kt-info-box3383_612a39-98 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3383_612a39-98 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-color:var(--global-palette7, #eeeeee);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box3383_612a39-98 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box3383_612a39-98 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);border-color:var(--global-palette9, #ffffff);}.kt-info-box3383_612a39-98 .kt-infobox-textcontent h5.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3383_612a39-98 h5.kt-blocks-info-box-title{min-height:27px;}.kt-info-box3383_612a39-98 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette8, #F7FAFC);}.wp-block-kadence-infobox.kt-info-box3383_612a39-98 .kt-blocks-info-box-text{font-size:var(--global-kb-font-size-md, 1.25rem);letter-spacing:-1px;font-family:var( --global-body-font-family, inherit );font-style:normal;margin-top:24px;margin-right:24px;margin-bottom:24px;margin-left:24px;}.kt-info-box3383_612a39-98 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3383_612a39-98 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3383_612a39-98\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_document kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v8h7v-4h-4v-4h-3zm4 0v3h3l-3-3zm-3 2h1v1h-1v-1zm0 2h1v1h-1v-1zm0 2h4v1h-4v-1z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h5 class=\"kt-blocks-info-box-title\"><strong>Especializaci\u00f3n en el trabajo con extranjeros<\/strong><\/h5><p class=\"kt-blocks-info-box-text\">Conocemos la especificidad de las normas relativas a los ciudadanos de terceros pa\u00edses, incluidos Ucrania, Bielorrusia y otros estados.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><style>.kadence-column3383_c77429-ab > .kt-inside-inner-col,.kadence-column3383_c77429-ab > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3383_c77429-ab > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_c77429-ab > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_c77429-ab > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_c77429-ab > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3383_c77429-ab > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3383_c77429-ab{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_c77429-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_c77429-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_c77429-ab\"><div class=\"kt-inside-inner-col\"><style>.kadence-column3383_ba2620-9e > .kt-inside-inner-col{min-height:300px;box-shadow:5px 5px 10px 0px var(--global-palette6, #718096);}.kadence-column3383_ba2620-9e > .kt-inside-inner-col,.kadence-column3383_ba2620-9e > .kt-inside-inner-col:before{border-top-left-radius:19px;border-top-right-radius:19px;border-bottom-right-radius:19px;border-bottom-left-radius:19px;}.kadence-column3383_ba2620-9e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_ba2620-9e > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_ba2620-9e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_ba2620-9e > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3383_ba2620-9e:hover > .kt-inside-inner-col{background-color:var(--global-palette1, #3182CE);background-image:none;}.kadence-column3383_ba2620-9e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3383_ba2620-9e:hover, .kadence-column3383_ba2620-9e:hover h1, .kadence-column3383_ba2620-9e:hover h2, .kadence-column3383_ba2620-9e:hover h3, .kadence-column3383_ba2620-9e:hover h4, .kadence-column3383_ba2620-9e:hover h5, .kadence-column3383_ba2620-9e:hover h6{color:var(--global-palette9, #ffffff);}.kadence-column3383_ba2620-9e{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_ba2620-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_ba2620-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_ba2620-9e kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3383_0d5342-93 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3383_0d5342-93 .kt-blocks-info-box-link-wrap{border-top-left-radius:15px;border-top-right-radius:15px;background:rgba(223,223,223,0);padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box3383_0d5342-93 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3383_0d5342-93 .kt-info-svg-icon-flip, .kt-info-box3383_0d5342-93 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3383_0d5342-93 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-color:var(--global-palette7, #eeeeee);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box3383_0d5342-93 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box3383_0d5342-93 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);border-color:var(--global-palette9, #ffffff);}.kt-info-box3383_0d5342-93 .kt-infobox-textcontent h5.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3383_0d5342-93 h5.kt-blocks-info-box-title{min-height:27px;}.kt-info-box3383_0d5342-93 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette8, #F7FAFC);}.wp-block-kadence-infobox.kt-info-box3383_0d5342-93 .kt-blocks-info-box-text{font-size:var(--global-kb-font-size-md, 1.25rem);letter-spacing:-1px;font-family:var( --global-body-font-family, inherit );font-style:normal;margin-top:24px;margin-right:24px;margin-bottom:24px;margin-left:24px;}.kt-info-box3383_0d5342-93 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3383_0d5342-93 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3383_0d5342-93\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_file-import kt-info-svg-icon\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M16 288c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h112v-64H16zm336-152V0H152c-13.3 0-24 10.7-24 24v264h127.99v-65.18c0-14.28 17.29-21.41 27.36-11.27l95.7 96.43c6.6 6.65 6.6 17.39 0 24.04l-95.7 96.42c-10.06 10.14-27.36 3.01-27.36-11.27V352H128v136c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H376c-13.2 0-24-10.8-24-24zm153-31L407.1 7c-4.5-4.5-10.6-7-17-7H384v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h5 class=\"kt-blocks-info-box-title\"><strong>Enfoque integral para cada caso<\/strong><\/h5><p class=\"kt-blocks-info-box-text\">Ofrecemos no solo asesoramiento, sino tambi\u00e9n un apoyo completo en cada etapa en la comunicaci\u00f3n con las autoridades. <br\/><br\/><\/p><\/div><\/span><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><style>.kadence-column3383_59bc48-2a > .kt-inside-inner-col{min-height:300px;box-shadow:5px 5px 10px 0px var(--global-palette6, #718096);}.kadence-column3383_59bc48-2a > .kt-inside-inner-col,.kadence-column3383_59bc48-2a > .kt-inside-inner-col:before{border-top-left-radius:19px;border-top-right-radius:19px;border-bottom-right-radius:19px;border-bottom-left-radius:19px;}.kadence-column3383_59bc48-2a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_59bc48-2a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_59bc48-2a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_59bc48-2a > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3383_59bc48-2a:hover > .kt-inside-inner-col{background-color:var(--global-palette1, #3182CE);background-image:none;}.kadence-column3383_59bc48-2a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3383_59bc48-2a:hover, .kadence-column3383_59bc48-2a:hover h1, .kadence-column3383_59bc48-2a:hover h2, .kadence-column3383_59bc48-2a:hover h3, .kadence-column3383_59bc48-2a:hover h4, .kadence-column3383_59bc48-2a:hover h5, .kadence-column3383_59bc48-2a:hover h6{color:var(--global-palette9, #ffffff);}.kadence-column3383_59bc48-2a{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_59bc48-2a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_59bc48-2a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_59bc48-2a kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3383_57294e-d3 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3383_57294e-d3 .kt-blocks-info-box-link-wrap{border-top-left-radius:15px;border-top-right-radius:15px;background:rgba(223,223,223,0);padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kt-info-box3383_57294e-d3 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3383_57294e-d3 .kt-info-svg-icon-flip, .kt-info-box3383_57294e-d3 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3383_57294e-d3 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-color:var(--global-palette7, #eeeeee);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box3383_57294e-d3 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box3383_57294e-d3 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);border-color:var(--global-palette9, #ffffff);}.kt-info-box3383_57294e-d3 .kt-infobox-textcontent h5.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3383_57294e-d3 h5.kt-blocks-info-box-title{min-height:27px;}.kt-info-box3383_57294e-d3 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette8, #F7FAFC);}.wp-block-kadence-infobox.kt-info-box3383_57294e-d3 .kt-blocks-info-box-text{font-size:var(--global-kb-font-size-md, 1.25rem);letter-spacing:-1px;font-family:var( --global-body-font-family, inherit );font-style:normal;margin-top:24px;margin-right:24px;margin-bottom:24px;margin-left:24px;}.kt-info-box3383_57294e-d3 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3383_57294e-d3 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3383_57294e-d3\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_user-tie kt-info-svg-icon\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm95.8 32.6L272 480l-32-136 32-56h-96l32 56-32 136-47.8-191.4C56.9 292 0 350.3 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-72.1-56.9-130.4-128.2-133.8z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h5 class=\"kt-blocks-info-box-title\"><strong>Seguridad y confianza<\/strong><\/h5><p class=\"kt-blocks-info-box-text\">Ayudamos a evitar errores que pueden acarrear sanciones econ\u00f3micas o problemas legales. <br\/><br\/><\/p><\/div><\/span><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3383_2cd6ae-c4 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:0px;padding-left:10px;}.kadence-column3383_2cd6ae-c4 > .kt-inside-inner-col,.kadence-column3383_2cd6ae-c4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3383_2cd6ae-c4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3383_2cd6ae-c4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3383_2cd6ae-c4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3383_2cd6ae-c4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3383_2cd6ae-c4{position:relative;}@media all and (max-width: 1024px){.kadence-column3383_2cd6ae-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3383_2cd6ae-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3383_2cd6ae-c4 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3383_84efc8-3c .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-3383_84efc8-3c .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:40px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3383_84efc8-3c\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3383_a328d2-72, .wp-block-kadence-advancedheading.kt-adv-heading3383_a328d2-72[data-kb-block=\"kb-adv-heading3383_a328d2-72\"]{margin-top:-10px;margin-right:0px;margin-bottom:0px;margin-left:0px;text-align:center;line-height:1em;font-weight:500;font-style:normal;font-family:Inter;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3383_a328d2-72 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3383_a328d2-72[data-kb-block=\"kb-adv-heading3383_a328d2-72\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3383_a328d2-72 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3383_a328d2-72[data-kb-block=\"kb-adv-heading3383_a328d2-72\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3383_a328d2-72, .wp-block-kadence-advancedheading.kt-adv-heading3383_a328d2-72[data-kb-block=\"kb-adv-heading3383_a328d2-72\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading3383_a328d2-72 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3383_a328d2-72\">CONTACTO<\/h4>\n<\/div><\/div>\n<\/div><\/div>\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id2401_341dd5-be{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id2401_341dd5-be > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2401_341dd5-be > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2401_341dd5-be > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:1250px;margin-left:auto;margin-right:auto;padding-top:51px;padding-right:0px;padding-bottom:22px;padding-left:0px;grid-template-columns:minmax(0, calc(40% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(60% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id2401_341dd5-be{background-image:url('https:\/\/old.pcr-legal.pl\/wp-content\/uploads\/2024\/01\/02.png');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id2401_341dd5-be > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2401_341dd5-be > .kt-row-column-wrap{padding-top:80px;padding-right:20px;padding-bottom:80px;padding-left:20px;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id2401_341dd5-be > .kt-row-column-wrap{padding-top:60px;padding-right:20px;padding-bottom:60px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2401_341dd5-be alignnone has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column2401_9aa931-1a > .kt-inside-inner-col{display:flex;}.kadence-column2401_9aa931-1a > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column2401_9aa931-1a > .kt-inside-inner-col,.kadence-column2401_9aa931-1a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2401_9aa931-1a > .kt-inside-inner-col{row-gap:0px;column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2401_9aa931-1a > .kt-inside-inner-col{flex-direction:column;}.kadence-column2401_9aa931-1a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2401_9aa931-1a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2401_9aa931-1a{position:relative;}@media all and (max-width: 1024px){.kadence-column2401_9aa931-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2401_9aa931-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2401_9aa931-1a inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kadence-column2401_06bf07-46 > .kt-inside-inner-col{display:flex;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col,.kadence-column2401_06bf07-46 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col{row-gap:0px;column-gap:var(--global-kb-gap-none, 0rem );}.kadence-column2401_06bf07-46 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;flex-wrap:nowrap;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col > *, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2401_06bf07-46 a{color:var(--global-palette9, #ffffff);}.kadence-column2401_06bf07-46 a:hover{color:var(--global-palette2, #2B6CB0);}.kadence-column2401_06bf07-46{position:relative;}@media all and (max-width: 1024px){.kadence-column2401_06bf07-46 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;flex-wrap:nowrap;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column2401_06bf07-46 > .kt-inside-inner-col > *, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column2401_06bf07-46 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;flex-wrap:nowrap;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col > *, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column2401_06bf07-46 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column2401_06bf07-46 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2401_06bf07-46 kb-section-dir-horizontal inner-column-1\"><div class=\"kt-inside-inner-col\"><style id=\"wpforms-css-vars-2331-block-ed363ec0-d2eb-4ec5-a74c-166069c05f95\">\n\t\t\t\t#wpforms-2331.wpforms-block-ed363ec0-d2eb-4ec5-a74c-166069c05f95 {\n\t\t\t\t--wpforms-label-color: var(--global-palette9);\n--wpforms-label-sublabel-color: var(--global-palette9);\n--wpforms-field-text-color: var(--global-palette8);\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-ed363ec0-d2eb-4ec5-a74c-166069c05f95 wpforms-render-modern\" id=\"wpforms-2331\"><form id=\"wpforms-form-2331\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"2331\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/3980\" data-token=\"47adf575e95353a3028b5175a5d0e6eb\" data-token-time=\"1788357597\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\">\t\t<div id=\"wpforms-2331-field_1-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"1\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-2331-field_1\" >Consentimientos ponerte \u00bfC\u00f3mo<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-2331-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-2331-field_2-container\" class=\"wpforms-field wpforms-field-name form-name\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-2331-field_2\">Nombre <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2331-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-2331-field_2-error\" required><\/div><div id=\"wpforms-2331-field_3-container\" class=\"wpforms-field wpforms-field-email form-email\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-2331-field_3\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-2331-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-2331-field_3-error\" required><\/div><div id=\"wpforms-2331-field_5-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-2331-field_5\">\u00bfC\u00f3mo podemos ayudarte? Te invitamos a ponerte en contacto <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-2331-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" aria-errormessage=\"wpforms-2331-field_5-error\" required><\/textarea><\/div><div id=\"wpforms-2331-field_4-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"4\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Consentimientos <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-2331-field_4\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-2331-field_4_1\" name=\"wpforms[fields][4][]\" value=\"Autorizo el tratamiento de mis datos personales con el fin de gestionar mi consulta de acuerdo con\" aria-errormessage=\"wpforms-2331-field_4_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2331-field_4_1\">Autorizo el tratamiento de mis datos personales con el fin de gestionar mi consulta de acuerdo con<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-2331-field_7-container\" class=\"wpforms-field wpforms-field-text hide-field marketing-data-field\" data-field-id=\"7\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2331-field_7\" aria-hidden=\"false\">Marketing<\/label><input type=\"text\" id=\"wpforms-2331-field_7\" class=\"wpforms-field-large\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-2331-field_7-error\" ><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-2331-field_1-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-2331-field_1-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-2331-field_1-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-invisible\" ><div class=\"g-recaptcha\" data-sitekey=\"6LdKGqUpAAAAAOgcVz-d4IbEfW38vGIuyF1QS_MP\" data-size=\"invisible\"><\/div><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"2331\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/pages\/3980\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-2331\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/old.pcr-legal.pl\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column2401_20a729-ee > .kt-inside-inner-col{display:flex;}.kadence-column2401_20a729-ee > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kadence-column2401_20a729-ee > .kt-inside-inner-col,.kadence-column2401_20a729-ee > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2401_20a729-ee > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column2401_20a729-ee > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column2401_20a729-ee{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column2401_20a729-ee > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2401_20a729-ee{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column2401_20a729-ee{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column2401_20a729-ee{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column2401_20a729-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2401_20a729-ee\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-theme-palette-9-color has-text-color has-link-color has-large-font-size wp-elements-2 wp-block-paragraph\" style=\"text-transform:none\">\u00bfTienes preguntas? \u00bfQuieres utilizar el servicio?<\/p>\n\n\n\n<p class=\"has-theme-palette-9-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\">Escr\u00edbenos y un especialista se pondr\u00e1 en contacto contigo lo antes posible<\/p>\n\n\n<style>.kadence-column2401_094173-1c > .kt-inside-inner-col,.kadence-column2401_094173-1c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2401_094173-1c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2401_094173-1c > .kt-inside-inner-col{flex-direction:column;}.kadence-column2401_094173-1c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2401_094173-1c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2401_094173-1c{position:relative;}@media all and (max-width: 1024px){.kadence-column2401_094173-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2401_094173-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2401_094173-1c\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-theme-palette-2-color has-theme-palette-9-background-color has-text-color has-background has-link-color has-custom-font-size wp-element-button\" href=\"tel:+48572868879\" style=\"padding-top:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--50);font-size:16px\">Ll\u00e1manos<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-theme-palette-2-color has-theme-palette-9-background-color has-text-color has-background has-link-color has-custom-font-size wp-element-button\" href=\"https:\/\/www.google.com\/maps\/place\/Polskie+Centrum+Rezydencji\/@54.3400247,18.6568298,17z\/data=!4m6!3m5!1s0x46fd7383d87233ab:0xe51864d1f8dfb18b!8m2!3d54.3400216!4d18.6594047!16s%2Fg%2F11vk9g8_26?entry=ttu\" style=\"padding-top:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--50);font-size:16px\" target=\"_blank\" rel=\"noopener\">Encuentra nuestra oficina<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Asesoramiento en la contrataci\u00f3n de extranjeros La contrataci\u00f3n de trabajadores del extranjero es un proceso complejo y laborioso que requiere conocer la normativa polaca de derecho laboral y la legalizaci\u00f3n del empleo. Nuestro servicio de Asesoramiento en la Contrataci\u00f3n de Extranjeros es un apoyo que permite evitar errores, agilizar los tr\u00e1mites y proteger plenamente los&#8230;<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_kadence_starter_templates_imported_post":false,"_swpsp_post_exclude":false,"_kad_post_transparent":"enable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-3980","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/pages\/3980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/comments?post=3980"}],"version-history":[{"count":5,"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/pages\/3980\/revisions"}],"predecessor-version":[{"id":4516,"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/pages\/3980\/revisions\/4516"}],"wp:attachment":[{"href":"https:\/\/old.pcr-legal.pl\/es\/wp-json\/wp\/v2\/media?parent=3980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}